{"id":3578,"date":"2024-03-17T22:21:54","date_gmt":"2024-03-17T21:21:54","guid":{"rendered":"https:\/\/psicoterapiaberlino.de\/informativa-sulla-privacy\/"},"modified":"2024-06-19T22:29:10","modified_gmt":"2024-06-19T20:29:10","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/psicologoberlino.com\/de\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1>DATENSCHUTZERKL\u00c4RUNG<\/h1>\n<p><strong>DI WWW.PSICOLOGOBERLINO.COM<\/strong><\/p>\n<p>Questo Sito Web raccoglie alcuni Dati Personali dei propri Utenti.<\/p>\n<h2 id=\"owner_of_the_data\">TITOLARE DEL TRATTAMENTO DEI DATI<\/h2>\n<p>Caterina Nicolosi Gan\u00dfmann \u2013 Karl Schrader Str. 6 10781 Berlin Sch\u00f6neberg (Germania)<\/p>\n<p><b>Indirizzo email del Titolare:<\/b>\u00a0info@psicologoberlino.com<\/p>\n<h2 id=\"types_of_data\">TIPOLOGIE DI DATI RACCOLTI<\/h2>\n<p>Fra i Dati Personali raccolti da questo Sito Web, in modo autonomo o tramite terze parti, ci sono: Cookie, Dati di utilizzo, email e nome.<\/p>\n<p>Dettagli completi su ciascuna tipologia di dati raccolti sono forniti nelle sezioni dedicate di questa privacy policy o mediante specifici testi informativi visualizzati prima della raccolta dei dati stessi.<br \/>\nI Dati Personali possono essere liberamente forniti dall\u2019Utente o, nel caso di Dati di Utilizzo, raccolti automaticamente durante l\u2019uso di questo Sito Web.<br \/>\nSe non diversamente specificato, tutti i Dati richiesti da questo Sito Web sono obbligatori. Se l\u2019Utente rifiuta di comunicarli, potrebbe essere impossibile per questo Sito Web fornire il Servizio. Nei casi in cui questo Sito Web indichi alcuni Dati come facoltativi, gli Utenti sono liberi di astenersi dal comunicare tali Dati, senza che ci\u00f2 abbia alcuna conseguenza sulla disponibilit\u00e0 del Servizio o sulla sua operativit\u00e0.<br \/>\nGli Utenti che dovessero avere dubbi su quali Dati siano obbligatori, sono incoraggiati a contattare il Titolare.<br \/>\nL\u2019eventuale utilizzo di Cookie \u2013 o di altri strumenti di tracciamento \u2013 da parte di questo Sito Web o dei titolari dei servizi terzi utilizzati da questo Sito Web, ove non diversamente precisato, ha la finalit\u00e0 di fornire il Servizio richiesto dall\u2019Utente, oltre alle ulteriori finalit\u00e0 descritte nel presente documento e nella Cookie Policy, se disponibile.<\/p>\n<p>L\u2019Utente si assume la responsabilit\u00e0 dei Dati Personali di terzi ottenuti, pubblicati o condivisi mediante questo Sito Web e garantisce di avere il diritto di comunicarli o diffonderli, liberando il Titolare da qualsiasi responsabilit\u00e0 verso terzi.<\/p>\n<h2 id=\"place_of_processing\">MODALIT\u00c0 E LUOGO DEL TRATTAMENTO DEI DATI RACCOLTI<\/h2>\n<h3>MODALIT\u00c0 DI TRATTAMENTO<\/h3>\n<p>Il Titolare adotta le opportune misure di sicurezza volte ad impedire l\u2019accesso, la divulgazione, la modifica o la distruzione non autorizzate dei Dati Personali.<br \/>\nIl trattamento viene effettuato mediante strumenti informatici e\/o telematici, con modalit\u00e0 organizzative e con logiche strettamente correlate alle finalit\u00e0 indicate. Oltre al Titolare, in alcuni casi, potrebbero avere accesso ai Dati altri soggetti coinvolti nell\u2019organizzazione di questo Sito Web (personale amministrativo, commerciale, marketing, legali, amministratori di sistema) ovvero soggetti esterni (come fornitori di servizi tecnici terzi, corrieri postali, hosting provider, societ\u00e0 informatiche, agenzie di comunicazione) nominati anche, se necessario, Responsabili del Trattamento da parte del Titolare. L\u2019elenco aggiornato dei Responsabili potr\u00e0 sempre essere richiesto al Titolare del Trattamento.<\/p>\n<h3>BASE GIURIDICA DEL TRATTAMENTO<\/h3>\n<p>Il Titolare tratta Dati Personali relativi all\u2019Utente in caso sussista una delle seguenti condizioni:<\/p>\n<ul>\n<li>l\u2019Utente ha prestato il consenso per una o pi\u00f9 finalit\u00e0 specifiche; Nota: in alcuni ordinamenti il Titolare pu\u00f2 essere autorizzato a trattare Dati Personali senza che debba sussistere il consenso dell\u2019Utente o un\u2019altra delle basi giuridiche specificate di seguito, fino a quando l\u2019Utente non si opponga (\u201copt-out\u201d) a tale trattamento. Ci\u00f2 non \u00e8 tuttavia applicabile qualora il trattamento di Dati Personali sia regolato dalla legislazione europea in materia di protezione dei Dati Personali;<\/li>\n<li>il trattamento \u00e8 necessario all\u2019esecuzione di un contratto con l\u2019Utente e\/o all\u2019esecuzione di misure precontrattuali;<\/li>\n<li>il trattamento \u00e8 necessario per adempiere un obbligo legale al quale \u00e8 soggetto il Titolare;<\/li>\n<li>il trattamento \u00e8 necessario per l\u2019esecuzione di un compito di interesse pubblico o per l\u2019esercizio di pubblici poteri di cui \u00e8 investito il Titolare;<\/li>\n<li>il trattamento \u00e8 necessario per il perseguimento del legittimo interesse del Titolare o di terzi.<\/li>\n<\/ul>\n<p>E\u2019 comunque sempre possibile richiedere al Titolare di chiarire la concreta base giuridica di ciascun trattamento ed in particolare di specificare se il trattamento sia basato sulla legge, previsto da un contratto o necessario per concludere un contratto.<\/p>\n<h3>LUOGO<\/h3>\n<p>I Dati sono trattati presso le sedi operative del Titolare ed in ogni altro luogo in cui le parti coinvolte nel trattamento siano localizzate. Per ulteriori informazioni, contatta il Titolare.<br \/>\nI Dati Personali dell\u2019Utente potrebbero essere trasferiti in un paese diverso da quello in cui l\u2019Utente si trova. Per ottenere ulteriori informazioni sul luogo del trattamento l\u2019Utente pu\u00f2 fare riferimento alla sezione relativa ai dettagli sul trattamento dei Dati Personali.<\/p>\n<p>L\u2019Utente ha diritto a ottenere informazioni in merito alla base giuridica del trasferimento di Dati al di fuori dell\u2019Unione Europea o ad un\u2019organizzazione internazionale di diritto internazionale pubblico o costituita da due o pi\u00f9 paesi, come ad esempio l\u2019ONU, nonch\u00e9 in merito alle misure di sicurezza adottate dal Titolare per proteggere i Dati.<\/p>\n<p>Qualora abbia luogo uno dei trasferimenti appena descritti, l\u2019Utente pu\u00f2 fare riferimento alle rispettive sezioni di questo documento o chiedere informazioni al Titolare contattandolo agli estremi riportati in apertura.<\/p>\n<h3>PERIODO DI CONSERVAZIONE<\/h3>\n<p>I Dati sono trattati e conservati per il tempo richiesto dalle finalit\u00e0 per le quali sono stati raccolti.<\/p>\n<p>Pertanto:<\/p>\n<ul>\n<li>I Dati Personali raccolti per scopi collegati all\u2019esecuzione di un contratto tra il Titolare e l\u2019Utente saranno trattenuti sino a quando sia completata l\u2019esecuzione di tale contratto.<\/li>\n<li>I Dati Personali raccolti per finalit\u00e0 riconducibili all\u2019interesse legittimo del Titolare saranno trattenuti sino al soddisfacimento di tale interesse. L\u2019Utente pu\u00f2 ottenere ulteriori informazioni in merito all\u2019interesse legittimo perseguito dal Titolare nelle relative sezioni di questo documento o contattando il Titolare.<\/li>\n<\/ul>\n<p>Quando il trattamento \u00e8 basato sul consenso dell\u2019Utente, il Titolare pu\u00f2 conservare i Dati Personali pi\u00f9 a lungo sino a quando detto consenso non venga revocato. Inoltre il Titolare potrebbe essere obbligato a conservare i Dati Personali per un periodo pi\u00f9 lungo in ottemperanza ad un obbligo di legge o per ordine di un\u2019autorit\u00e0.<\/p>\n<p>Al termine del periodo di conservazioni i Dati Personali saranno cancellati. Pertanto, allo spirare di tale termine il diritto di accesso, cancellazione, rettificazione ed il diritto alla portabilit\u00e0 dei Dati non potranno pi\u00f9 essere esercitati.<\/p>\n<h2 id=\"use_collected_data\">FINALIT\u00c0 DEL TRATTAMENTO DEI DATI RACCOLTI<\/h2>\n<p>I Dati dell\u2019Utente sono raccolti per consentire al Titolare di fornire i propri Servizi, cos\u00ec come per le seguenti finalit\u00e0: Statistica, Visualizzazione di contenuti da piattaforme esterne, Gestione contatti e invio di messaggi, Contattare l\u2019Utente, Interazione con social network e piattaforme esterne, Heat mapping e registrazione sessioni, Remarketing e behavioral targeting e Affiliazione commerciale.<\/p>\n<p>Per ottenere ulteriori informazioni dettagliate sulle finalit\u00e0 del trattamento e sui Dati Personali concretamente rilevanti per ciascuna finalit\u00e0, l\u2019Utente pu\u00f2 fare riferimento alle relative sezioni di questo documento.<\/p>\n<h2 id=\"data_processing_detailed_info\">DETTAGLI SUL TRATTAMENTO DEI DATI PERSONALI<\/h2>\n<p>I Dati Personali sono raccolti per le seguenti finalit\u00e0 ed utilizzando i seguenti servizi:<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_4751411\">AFFILIAZIONE COMMERCIALE<\/h3>\n<p>Questo tipo di servizi consente a questo Sito Web di esporre annunci di prodotti o servizi offerti da terze parti. Gli annunci possono essere visualizzati sia sotto forma di link pubblicitari che sotto forma di banner in varie forme grafiche.<br \/>\nIl click sull\u2019icona o sul banner pubblicato su questo Sito Web sono tracciati dai servizi terzi elencati di seguito e vengono condivisi con questo Sito Web.<br \/>\nPer conoscere quali dati vengano raccolti si prega di far riferimento alle informative privacy di ciascun servizio.<\/p>\n<h4>AMAZON AFFILIATION (AMAZON)<\/h4>\n<p>Amazon Affiliation \u00e8 un servizio di affiliazione commerciale fornito da Amazon.com Inc.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.amazon.com\/gp\/help\/customer\/display.html\/ref=hp_rel_topic?ie=UTF8&amp;nodeId=468496\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_3581264\">CONTATTARE L\u2019UTENTE<\/h3>\n<h4>MODULO DI CONTATTO (QUESTO SITO WEB)<\/h4>\n<p>L\u2019Utente, compilando con i propri Dati il modulo di contatto, acconsente al loro utilizzo per rispondere alle richieste di informazioni, di preventivo, o di qualunque altra natura indicata dall\u2019intestazione del modulo.<\/p>\n<p>Dati Personali raccolti: email e nome.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_3581210\">GESTIONE CONTATTI E INVIO DI MESSAGGI<\/h3>\n<p>Questo tipo di servizi consente di gestire un database di contatti email, contatti telefonici o contatti di qualunque altro tipo, utilizzati per comunicare con l\u2019Utente.<br \/>\nQuesti servizi potrebbero inoltre consentire di raccogliere dati relativi alla data e all\u2019ora di visualizzazione dei messaggi da parte dell\u2019Utente, cos\u00ec come all\u2019interazione dell\u2019Utente con essi, come le informazioni sui click sui collegamenti inseriti nei messaggi.<\/p>\n<h4>MAILCHIMP (THE ROCKET SCIENCE GROUP, LLC.)<\/h4>\n<p>MailChimp \u00e8 un servizio di gestione indirizzi e invio di messaggi email fornito da The Rocket Science Group, LLC.<\/p>\n<p>Dati Personali raccolti: email.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/mailchimp.com\/legal\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_4751301\">HEAT MAPPING E REGISTRAZIONE SESSIONI<\/h3>\n<p>I servizi di heat mapping sono utilizzati per individuare quali aree di una pagina sono oggetto del passaggio del cursore o di click del mouse in modo da rilevare quali di esse attraggono il maggior interesse. Questi servizi permettono di monitorare e analizzare i dati di traffico e servono a tener traccia del comportamento dell\u2019Utente.<br \/>\nAlcuni di questi servizi potrebbero registrare le sessioni e renderle disponibili per visualizzarle in seguito.<\/p>\n<h4>SMARTLOOK (SMARTSUPP.COM, S.R.O.)<\/h4>\n<p>Smartlook \u00e8 un servizio di heat mapping e di registrazione delle sessioni fornito da Smartsupp.com, s.r.o.<\/p>\n<p>Dati Personali raccolti: Cookie, Dati di utilizzo e varie tipologie di Dati secondo quanto specificato dalla privacy policy del servizio.<\/p>\n<p>Luogo del trattamento: Repubblica Ceca \u2013\u00a0<a href=\"https:\/\/www.smartlook.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_3581367\">INTERAZIONE CON SOCIAL NETWORK E PIATTAFORME ESTERNE<\/h3>\n<p>Questo tipo di servizi permette di effettuare interazioni con i social network, o con altre piattaforme esterne, direttamente dalle pagine di questo Sito Web.<br \/>\nLe interazioni e le informazioni acquisite da questo Sito Web sono in ogni caso soggette alle impostazioni privacy dell\u2019Utente relative ad ogni social network.<br \/>\nNel caso in cui sia installato un servizio di interazione con i social network, \u00e8 possibile che, anche nel caso gli Utenti non utilizzino il servizio, lo stesso raccolga dati di traffico relativi alle pagine in cui \u00e8 installato.<\/p>\n<h4>PULSANTE E WIDGET SOCIALI DI LINKEDIN (LINKEDIN CORPORATION)<\/h4>\n<p>Il pulsante e i widget sociali di LinkedIn sono servizi di interazione con il social network Linkedin, forniti da LinkedIn Corporation.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h4>PULSANTE MI PIACE E WIDGET SOCIALI DI FACEBOOK (FACEBOOK, INC.)<\/h4>\n<p>Il pulsante \u201cMi Piace\u201d e i widget sociali di Facebook sono servizi di interazione con il social network Facebook, forniti da Facebook, Inc.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/www.facebook.com\/privacy\/explanation\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h4>PULSANTE TWEET E WIDGET SOCIALI DI TWITTER (TWITTER, INC.)<\/h4>\n<p>Il pulsante Tweet e i widget sociali di Twitter sono servizi di interazione con il social network Twitter, forniti da Twitter, Inc.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/twitter.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_4751312\">REMARKETING E BEHAVIORAL TARGETING<\/h3>\n<p>Questo tipo di servizi consente a questo Sito Web ed ai suoi partner di comunicare, ottimizzare e servire annunci pubblicitari basati sull\u2019utilizzo passato di questo Sito Web da parte dell\u2019Utente.<br \/>\nQuesta attivit\u00e0 viene effettuata tramite il tracciamento dei Dati di Utilizzo e l\u2019uso di Cookie, informazioni che vengono trasferite ai partner a cui l\u2019attivit\u00e0 di remarketing e behavioral targeting \u00e8 collegata.<br \/>\nIn aggiunta alle possibilit\u00e0 di effettuare l\u2019opt-out offerte dai servizi di seguito riportati, l\u2019Utente pu\u00f2 optare per l\u2019esclusione rispetto alla ricezione dei cookie relativi ad un servizio terzo, visitando la\u00a0<a href=\"http:\/\/optout.networkadvertising.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">pagina di opt-out del Network Advertising Initiative<\/a>.<\/p>\n<h4>ADWORDS REMARKETING (GOOGLE INC.)<\/h4>\n<p>AdWords Remarketing \u00e8 un servizio di remarketing e behavioral targeting fornito da Google Inc. che collega l\u2019attivit\u00e0 di questo Sito Web con il network di advertising Adwords ed il Cookie Doubleclick.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.google.com\/intl\/it\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/www.google.com\/settings\/ads\/onweb\/optout\" target=\"_blank\" rel=\"noopener noreferrer\">Opt Out<\/a>.<\/p>\n<h4>FACEBOOK CUSTOM AUDIENCE (FACEBOOK, INC.)<\/h4>\n<p>Facebook Custom Audience \u00e8 un servizio di remarketing e behavioral targeting fornito da Facebook, Inc. che collega l\u2019attivit\u00e0 di questo Sito Web con il network di advertising Facebook.<\/p>\n<p>Dati Personali raccolti: Cookie e email.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/www.aboutads.info\/choices\/\" target=\"_blank\" rel=\"noopener noreferrer\">Opt Out<\/a>. Soggetto aderente al Privacy Shield.<\/p>\n<h4>FACEBOOK REMARKETING (FACEBOOK, INC.)<\/h4>\n<p>Facebook Remarketing \u00e8 un servizio di remarketing e behavioral targeting fornito da Facebook, Inc. che collega l\u2019attivit\u00e0 di questo Sito Web con il network di advertising Facebook.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/www.aboutads.info\/choices\/\" target=\"_blank\" rel=\"noopener noreferrer\">Opt Out<\/a>. Soggetto aderente al Privacy Shield.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_3581198\">STATISTICA<\/h3>\n<p>I servizi contenuti nella presente sezione permettono al Titolare del Trattamento di monitorare e analizzare i dati di traffico e servono a tener traccia del comportamento dell\u2019Utente.<\/p>\n<h4>GOOGLE ANALYTICS CON IP ANONIMIZZATO (GOOGLE INC.)<\/h4>\n<p>Google Analytics \u00e8 un servizio di analisi web fornito da Google Inc. (\u201cGoogle\u201d). Google utilizza i Dati Personali raccolti allo scopo di tracciare ed esaminare l\u2019utilizzo di questo Sito Web, compilare report e condividerli con gli altri servizi sviluppati da Google.<br \/>\nGoogle potrebbe utilizzare i Dati Personali per contestualizzare e personalizzare gli annunci del proprio network pubblicitario.<br \/>\nQuesta integrazione di Google Analytics rende anonimo il tuo indirizzo IP. L\u2019anonimizzazione funziona abbreviando entro i confini degli stati membri dell\u2019Unione Europea o in altri Paesi aderenti all\u2019accordo sullo Spazio Economico Europeo l\u2019indirizzo IP degli Utenti. Solo in casi eccezionali, l\u2019indirizzo IP sar\u00e0 inviato ai server di Google ed abbreviato all\u2019interno degli Stati Uniti.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/www.google.com\/intl\/it\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=it\" target=\"_blank\" rel=\"noopener noreferrer\">Opt Out<\/a>.<\/p>\n<h4>MONITORAGGIO CONVERSIONI DI FACEBOOK ADS (FACEBOOK, INC.)<\/h4>\n<p>Il monitoraggio conversioni di Facebook Ads \u00e8 un servizio di statistiche fornito da Facebook, Inc. che collega i dati provenienti dal network di annunci Facebook con le azioni compiute all\u2019interno di questo Sito Web.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>. Soggetto aderente al Privacy Shield.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_3581208\">VISUALIZZAZIONE DI CONTENUTI DA PIATTAFORME ESTERNE<\/h3>\n<p>Questo tipo di servizi permette di visualizzare contenuti ospitati su piattaforme esterne direttamente dalle pagine di questo Sito Web e di interagire con essi.<br \/>\nNel caso in cui sia installato un servizio di questo tipo, \u00e8 possibile che, anche nel caso gli Utenti non utilizzino il servizio, lo stesso raccolga dati di traffico relativi alle pagine in cui \u00e8 installato.<\/p>\n<h4>VIDEO VIMEO (VIMEO, LLC)<\/h4>\n<p>Vimeo \u00e8 un servizio di visualizzazione di contenuti video gestito da Vimeo, LLC che permette a questo Sito Web di integrare tali contenuti all\u2019interno delle proprie pagine.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h4>WIDGET GOOGLE MAPS (GOOGLE INC.)<\/h4>\n<p>Google Maps \u00e8 un servizio di visualizzazione di mappe gestito da Google Inc. che permette a questo Sito Web di integrare tali contenuti all\u2019interno delle proprie pagine.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.google.it\/intl\/it\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>. Soggetto aderente al Privacy Shield.<\/p>\n<h2>DIRITTI DELL\u2019UTENTE<\/h2>\n<p>Gli Utenti possono esercitare determinati diritti con riferimento ai Dati trattati dal Titolare.<\/p>\n<p>In particolare, l\u2019Utente ha il diritto di:<\/p>\n<ul>\n<li><b>revocare il consenso in ogni momento.<\/b>\u00a0L\u2019Utente pu\u00f2 revocare il consenso al trattamento dei propri Dati Personali precedentemente espresso.<\/li>\n<li><b>opporsi al trattamento dei propri Dati.<\/b>\u00a0L\u2019Utente pu\u00f2 opporsi al trattamento dei propri Dati quando esso avviene su una base giuridica diversa dal consenso. Ulteriori dettagli sul diritto di opposizione sono indicati nella sezione sottostante.<\/li>\n<li><b>accedere ai propri Dati.<\/b>\u00a0L\u2019Utente ha diritto ad ottenere informazioni sui Dati trattati dal Titolare, su determinati aspetti del trattamento ed a ricevere una copia dei Dati trattati.<\/li>\n<li><b>verificare e chiedere la rettificazione.<\/b>\u00a0L\u2019Utente pu\u00f2 verificare la correttezza dei propri Dati e richiederne l\u2019aggiornamento o la correzione.<\/li>\n<li><b>ottenere la limitazione del trattamento.<\/b>\u00a0Quando ricorrono determinate condizioni, l\u2019Utente pu\u00f2 richiedere la limitazione del trattamento dei propri Dati. In tal caso il Titolare non tratter\u00e0 i Dati per alcun altro scopo se non la loro conservazione.<\/li>\n<li><b>ottenere la cancellazione o rimozione dei propri Dati Personali.<\/b>\u00a0Quando ricorrono determinate condizioni, l\u2019Utente pu\u00f2 richiedere la cancellazione dei propri Dati da parte del Titolare.<\/li>\n<li><b>ricevere i propri Dati o farli trasferire ad altro titolare.<\/b>\u00a0L\u2019Utente ha diritto di ricevere i propri Dati in formato strutturato, di uso comune e leggibile da dispositivo automatico e, ove tecnicamente fattibile, di ottenerne il trasferimento senza ostacoli ad un altro titolare. Questa disposizione \u00e8 applicabile quando i Dati sono trattati con strumenti automatizzati ed il trattamento \u00e8 basato sul consenso dell\u2019Utente, su un contratto di cui l\u2019Utente \u00e8 parte o su misure contrattuali ad esso connesse.<\/li>\n<li><b>proporre reclamo.<\/b>\u00a0L\u2019Utente pu\u00f2 proporre un reclamo all\u2019autorit\u00e0 di controllo della protezione dei dati personali competente o agire in sede giudiziale.<\/li>\n<\/ul>\n<h3>DETTAGLI SUL DIRITTO DI OPPOSIZIONE<\/h3>\n<p>Quando i Dati Personali sono trattati nell\u2019interesse pubblico, nell\u2019esercizio di pubblici poteri di cui \u00e8 investito il Titolare oppure per perseguire un interesse legittimo del Titolare, gli Utenti hanno diritto ad opporsi al trattamento per motivi connessi alla loro situazione particolare.<\/p>\n<p>Si fa presente agli Utenti che, ove i loro Dati fossero trattati con finalit\u00e0 di marketing diretto, possono opporsi al trattamento senza fornire alcuna motivazione. Per scoprire se il Titolare tratti dati con finalit\u00e0 di marketing diretto gli Utenti possono fare riferimento alle rispettive sezioni di questo documento.<\/p>\n<h3>COME ESERCITARE I DIRITTI<\/h3>\n<p>Per esercitare i diritti dell\u2019Utente, gli Utenti possono indirizzare una richiesta agli estremi di contatto del Titolare indicati in questo documento. Le richieste sono depositate a titolo gratuito e evase dal Titolare nel pi\u00f9 breve tempo possibile, in ogni caso entro un mese.<\/p>\n<h2 id=\"cookie_policy\">COOKIE POLICY<\/h2>\n<p>Questo Sito Web fa utilizzo di Cookie. Per saperne di pi\u00f9 e per prendere visione dell\u2019informativa dettagliata, l\u2019Utente pu\u00f2 consultare la\u00a0<a class=\"show_comp_link iframe-preserve an-preserve\" title=\"Cookie Policy\" href=\"https:\/\/www.psicologoberlino.com\/cookie\">Cookie Policy<\/a>.<\/p>\n<h2 id=\"further_data_processing_info\">ULTERIORI INFORMAZIONI SUL TRATTAMENTO<\/h2>\n<h3>DIFESA IN GIUDIZIO<\/h3>\n<p>I Dati Personali dell\u2019Utente possono essere utilizzati da parte del Titolare in giudizio o nelle fasi preparatorie alla sua eventuale instaurazione per la difesa da abusi nell\u2019utilizzo di questo Sito Web o dei Servizi connessi da parte dell\u2019Utente.<br \/>\nL\u2019Utente dichiara di essere consapevole che il Titolare potrebbe essere obbligato a rivelare i Dati per ordine delle autorit\u00e0 pubbliche.<\/p>\n<h3>INFORMATIVE SPECIFICHE<\/h3>\n<p>Su richiesta dell\u2019Utente, in aggiunta alle informazioni contenute in questa privacy policy, questo Sito Web potrebbe fornire all\u2019Utente delle informative aggiuntive e contestuali riguardanti Servizi specifici, o la raccolta ed il trattamento di Dati Personali.<\/p>\n<h3>LOG DI SISTEMA E MANUTENZIONE<\/h3>\n<p>Per necessit\u00e0 legate al funzionamento ed alla manutenzione, questo Sito Web e gli eventuali servizi terzi da essa utilizzati potrebbero raccogliere Log di sistema, ossia file che registrano le interazioni e che possono contenere anche Dati Personali, quali l\u2019indirizzo IP Utente.<\/p>\n<h3>INFORMAZIONI NON CONTENUTE IN QUESTA POLICY<\/h3>\n<p>Ulteriori informazioni in relazione al trattamento dei Dati Personali potranno essere richieste in qualsiasi momento al Titolare del Trattamento utilizzando gli estremi di contatto.<\/p>\n<h3>RISPOSTA ALLE RICHIESTE \u201eDO NOT TRACK\u201d<\/h3>\n<p>Questo Sito Web non supporta le richieste \u201cDo Not Track\u201d.<br \/>\nPer scoprire se gli eventuali servizi di terze parti utilizzati le supportino, l\u2019Utente \u00e8 invitato a consultare le rispettive privacy policy.<\/p>\n<h3>MODIFICHE A QUESTA PRIVACY POLICY<\/h3>\n<p>Il Titolare del Trattamento si riserva il diritto di apportare modifiche alla presente privacy policy in qualunque momento dandone informazione agli Utenti su questa pagina e, se possibile, su questo Sito Web nonch\u00e9, qualora tecnicamente e legalmente fattibile, inviando una notifica agli Utenti attraverso uno degli estremi di contatto di cui \u00e8 in possesso il Titolare . Si prega dunque di consultare regolarmente questa pagina, facendo riferimento alla data di ultima modifica indicata in fondo.<\/p>\n<p>Qualora le modifiche interessino trattamenti la cui base giuridica \u00e8 il consenso, il Titolare provveder\u00e0 a raccogliere nuovamente il consenso dell\u2019Utente, se necessario.<\/p>\n<h3 class=\"expand-click w_icon_24 icon_ribbon\">DEFINIZIONI E RIFERIMENTI LEGALI<\/h3>\n<h4>DATI PERSONALI (O DATI)<\/h4>\n<p>Costituisce dato personale qualunque informazione che, direttamente o indirettamente, anche in collegamento con qualsiasi altra informazione, ivi compreso un numero di identificazione personale, renda identificata o identificabile una persona fisica.<\/p>\n<h4>DATI DI UTILIZZO<\/h4>\n<p>Sono le informazioni raccolte automaticamente attraverso questo Sito Web (anche da applicazioni di parti terze integrate in questo Sito Web), tra cui: gli indirizzi IP o i nomi a dominio dei computer utilizzati dall\u2019Utente che si connette con questo Sito Web, gli indirizzi in notazione URI (Uniform Resource Identifier), l\u2019orario della richiesta, il metodo utilizzato nell\u2019inoltrare la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta dal server (buon fine, errore, ecc.) il paese di provenienza, le caratteristiche del browser e del sistema operativo utilizzati dal visitatore, le varie connotazioni temporali della visita (ad esempio il tempo di permanenza su ciascuna pagina) e i dettagli relativi all\u2019itinerario seguito all\u2019interno dell\u2019Applicazione, con particolare riferimento alla sequenza delle pagine consultate, ai parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019Utente.<\/p>\n<h4>UTENTE<\/h4>\n<p>L\u2019individuo che utilizza questo Sito Web che, salvo ove diversamente specificato, coincide con l\u2019Interessato.<\/p>\n<h4>INTERESSATO<\/h4>\n<p>La persona fisica cui si riferiscono i Dati Personali.<\/p>\n<h4>RESPONSABILE DEL TRATTAMENTO (O RESPONSABILE)<\/h4>\n<p>La persona fisica, giuridica, la pubblica amministrazione e qualsiasi altro ente che tratta dati personali per conto del Titolare, secondo quanto esposto nella presente privacy policy.<\/p>\n<h4>TITOLARE DEL TRATTAMENTO (O TITOLARE)<\/h4>\n<p>La persona fisica o giuridica, l\u2019autorit\u00e0 pubblica, il servizio o altro organismo che, singolarmente o insieme ad altri, determina le finalit\u00e0 e i mezzi del trattamento di dati personali e gli strumenti adottati, ivi comprese le misure di sicurezza relative al funzionamento ed alla fruizione di questo Sito Web. Il Titolare del Trattamento, salvo quanto diversamente specificato, \u00e8 il titolare di questo Sito Web.<\/p>\n<h4>QUESTO SITO WEB (O QUESTA APPLICAZIONE)<\/h4>\n<p>Lo strumento hardware o software mediante il quale sono raccolti e trattati i Dati Personali degli Utenti.<\/p>\n<h4>SERVIZIO<\/h4>\n<p>Il Servizio fornito da questo Sito Web cos\u00ec come definito nei relativi termini (se presenti) su questo sito\/applicazione.<\/p>\n<h4>UNIONE EUROPEA (O UE)<\/h4>\n<p>Salvo ove diversamente specificato, ogni riferimento all\u2019Unione Europea contenuto in questo documento si intende esteso a tutti gli attuali stati membri dell\u2019Unione Europea e dello Spazio Economico Europeo.<\/p>\n<h4>COOKIE<\/h4>\n<p>Piccola porzione di dati conservata all\u2019interno del dispositivo dell\u2019Utente.<\/p>\n<hr \/>\n<h4>RIFERIMENTI LEGALI<\/h4>\n<p>La presente informativa privacy \u00e8 redatta sulla base di molteplici ordinamenti legislativi, inclusi gli artt. 13 e 14 del Regolamento (UE) 2016\/679.<\/p>\n<p>Ove non diversamente specificato, questa informativa privacy riguarda esclusivamente questo Sito Web.<\/p>\n<p>&nbsp;<\/p>\n<p>Ultima modifica del documento: 26\/11\/2019[\/vc_column_text][vc_column_text]<\/p>\n<h1>PRIVACY POLICY<\/h1>\n<p><strong>DI WWW.PSICOLOGOBERLINO.COM<\/strong><\/p>\n<p>Questo Sito Web raccoglie alcuni Dati Personali dei propri Utenti.<\/p>\n<h2 id=\"owner_of_the_data\">TITOLARE DEL TRATTAMENTO DEI DATI<\/h2>\n<p>Caterina Nicolosi Gan\u00dfmann \u2013 Karl Schrader Str. 6 10781 Berlin Sch\u00f6neberg (Germania)<\/p>\n<p><b>Indirizzo email del Titolare:<\/b>\u00a0info@psicologoberlino.com<\/p>\n<h2 id=\"types_of_data\">TIPOLOGIE DI DATI RACCOLTI<\/h2>\n<p>Fra i Dati Personali raccolti da questo Sito Web, in modo autonomo o tramite terze parti, ci sono: Cookie, Dati di utilizzo, email e nome.<\/p>\n<p>Dettagli completi su ciascuna tipologia di dati raccolti sono forniti nelle sezioni dedicate di questa privacy policy o mediante specifici testi informativi visualizzati prima della raccolta dei dati stessi.<br \/>\nI Dati Personali possono essere liberamente forniti dall\u2019Utente o, nel caso di Dati di Utilizzo, raccolti automaticamente durante l\u2019uso di questo Sito Web.<br \/>\nSe non diversamente specificato, tutti i Dati richiesti da questo Sito Web sono obbligatori. Se l\u2019Utente rifiuta di comunicarli, potrebbe essere impossibile per questo Sito Web fornire il Servizio. Nei casi in cui questo Sito Web indichi alcuni Dati come facoltativi, gli Utenti sono liberi di astenersi dal comunicare tali Dati, senza che ci\u00f2 abbia alcuna conseguenza sulla disponibilit\u00e0 del Servizio o sulla sua operativit\u00e0.<br \/>\nGli Utenti che dovessero avere dubbi su quali Dati siano obbligatori, sono incoraggiati a contattare il Titolare.<br \/>\nL\u2019eventuale utilizzo di Cookie \u2013 o di altri strumenti di tracciamento \u2013 da parte di questo Sito Web o dei titolari dei servizi terzi utilizzati da questo Sito Web, ove non diversamente precisato, ha la finalit\u00e0 di fornire il Servizio richiesto dall\u2019Utente, oltre alle ulteriori finalit\u00e0 descritte nel presente documento e nella Cookie Policy, se disponibile.<\/p>\n<p>L\u2019Utente si assume la responsabilit\u00e0 dei Dati Personali di terzi ottenuti, pubblicati o condivisi mediante questo Sito Web e garantisce di avere il diritto di comunicarli o diffonderli, liberando il Titolare da qualsiasi responsabilit\u00e0 verso terzi.<\/p>\n<h2 id=\"place_of_processing\">MODALIT\u00c0 E LUOGO DEL TRATTAMENTO DEI DATI RACCOLTI<\/h2>\n<h3>MODALIT\u00c0 DI TRATTAMENTO<\/h3>\n<p>Il Titolare adotta le opportune misure di sicurezza volte ad impedire l\u2019accesso, la divulgazione, la modifica o la distruzione non autorizzate dei Dati Personali.<br \/>\nIl trattamento viene effettuato mediante strumenti informatici e\/o telematici, con modalit\u00e0 organizzative e con logiche strettamente correlate alle finalit\u00e0 indicate. Oltre al Titolare, in alcuni casi, potrebbero avere accesso ai Dati altri soggetti coinvolti nell\u2019organizzazione di questo Sito Web (personale amministrativo, commerciale, marketing, legali, amministratori di sistema) ovvero soggetti esterni (come fornitori di servizi tecnici terzi, corrieri postali, hosting provider, societ\u00e0 informatiche, agenzie di comunicazione) nominati anche, se necessario, Responsabili del Trattamento da parte del Titolare. L\u2019elenco aggiornato dei Responsabili potr\u00e0 sempre essere richiesto al Titolare del Trattamento.<\/p>\n<h3>BASE GIURIDICA DEL TRATTAMENTO<\/h3>\n<p>Il Titolare tratta Dati Personali relativi all\u2019Utente in caso sussista una delle seguenti condizioni:<\/p>\n<ul>\n<li>l\u2019Utente ha prestato il consenso per una o pi\u00f9 finalit\u00e0 specifiche; Nota: in alcuni ordinamenti il Titolare pu\u00f2 essere autorizzato a trattare Dati Personali senza che debba sussistere il consenso dell\u2019Utente o un\u2019altra delle basi giuridiche specificate di seguito, fino a quando l\u2019Utente non si opponga (\u201copt-out\u201d) a tale trattamento. Ci\u00f2 non \u00e8 tuttavia applicabile qualora il trattamento di Dati Personali sia regolato dalla legislazione europea in materia di protezione dei Dati Personali;<\/li>\n<li>il trattamento \u00e8 necessario all\u2019esecuzione di un contratto con l\u2019Utente e\/o all\u2019esecuzione di misure precontrattuali;<\/li>\n<li>il trattamento \u00e8 necessario per adempiere un obbligo legale al quale \u00e8 soggetto il Titolare;<\/li>\n<li>il trattamento \u00e8 necessario per l\u2019esecuzione di un compito di interesse pubblico o per l\u2019esercizio di pubblici poteri di cui \u00e8 investito il Titolare;<\/li>\n<li>il trattamento \u00e8 necessario per il perseguimento del legittimo interesse del Titolare o di terzi.<\/li>\n<\/ul>\n<p>E\u2019 comunque sempre possibile richiedere al Titolare di chiarire la concreta base giuridica di ciascun trattamento ed in particolare di specificare se il trattamento sia basato sulla legge, previsto da un contratto o necessario per concludere un contratto.<\/p>\n<h3>LUOGO<\/h3>\n<p>I Dati sono trattati presso le sedi operative del Titolare ed in ogni altro luogo in cui le parti coinvolte nel trattamento siano localizzate. Per ulteriori informazioni, contatta il Titolare.<br \/>\nI Dati Personali dell\u2019Utente potrebbero essere trasferiti in un paese diverso da quello in cui l\u2019Utente si trova. Per ottenere ulteriori informazioni sul luogo del trattamento l\u2019Utente pu\u00f2 fare riferimento alla sezione relativa ai dettagli sul trattamento dei Dati Personali.<\/p>\n<p>L\u2019Utente ha diritto a ottenere informazioni in merito alla base giuridica del trasferimento di Dati al di fuori dell\u2019Unione Europea o ad un\u2019organizzazione internazionale di diritto internazionale pubblico o costituita da due o pi\u00f9 paesi, come ad esempio l\u2019ONU, nonch\u00e9 in merito alle misure di sicurezza adottate dal Titolare per proteggere i Dati.<\/p>\n<p>Qualora abbia luogo uno dei trasferimenti appena descritti, l\u2019Utente pu\u00f2 fare riferimento alle rispettive sezioni di questo documento o chiedere informazioni al Titolare contattandolo agli estremi riportati in apertura.<\/p>\n<h3>PERIODO DI CONSERVAZIONE<\/h3>\n<p>I Dati sono trattati e conservati per il tempo richiesto dalle finalit\u00e0 per le quali sono stati raccolti.<\/p>\n<p>Pertanto:<\/p>\n<ul>\n<li>I Dati Personali raccolti per scopi collegati all\u2019esecuzione di un contratto tra il Titolare e l\u2019Utente saranno trattenuti sino a quando sia completata l\u2019esecuzione di tale contratto.<\/li>\n<li>I Dati Personali raccolti per finalit\u00e0 riconducibili all\u2019interesse legittimo del Titolare saranno trattenuti sino al soddisfacimento di tale interesse. L\u2019Utente pu\u00f2 ottenere ulteriori informazioni in merito all\u2019interesse legittimo perseguito dal Titolare nelle relative sezioni di questo documento o contattando il Titolare.<\/li>\n<\/ul>\n<p>Quando il trattamento \u00e8 basato sul consenso dell\u2019Utente, il Titolare pu\u00f2 conservare i Dati Personali pi\u00f9 a lungo sino a quando detto consenso non venga revocato. Inoltre il Titolare potrebbe essere obbligato a conservare i Dati Personali per un periodo pi\u00f9 lungo in ottemperanza ad un obbligo di legge o per ordine di un\u2019autorit\u00e0.<\/p>\n<p>Al termine del periodo di conservazioni i Dati Personali saranno cancellati. Pertanto, allo spirare di tale termine il diritto di accesso, cancellazione, rettificazione ed il diritto alla portabilit\u00e0 dei Dati non potranno pi\u00f9 essere esercitati.<\/p>\n<h2 id=\"use_collected_data\">FINALIT\u00c0 DEL TRATTAMENTO DEI DATI RACCOLTI<\/h2>\n<p>I Dati dell\u2019Utente sono raccolti per consentire al Titolare di fornire i propri Servizi, cos\u00ec come per le seguenti finalit\u00e0: Statistica, Visualizzazione di contenuti da piattaforme esterne, Gestione contatti e invio di messaggi, Contattare l\u2019Utente, Interazione con social network e piattaforme esterne, Heat mapping e registrazione sessioni, Remarketing e behavioral targeting e Affiliazione commerciale.<\/p>\n<p>Per ottenere ulteriori informazioni dettagliate sulle finalit\u00e0 del trattamento e sui Dati Personali concretamente rilevanti per ciascuna finalit\u00e0, l\u2019Utente pu\u00f2 fare riferimento alle relative sezioni di questo documento.<\/p>\n<h2 id=\"data_processing_detailed_info\">DETTAGLI SUL TRATTAMENTO DEI DATI PERSONALI<\/h2>\n<p>I Dati Personali sono raccolti per le seguenti finalit\u00e0 ed utilizzando i seguenti servizi:<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_4751411\">AFFILIAZIONE COMMERCIALE<\/h3>\n<p>Questo tipo di servizi consente a questo Sito Web di esporre annunci di prodotti o servizi offerti da terze parti. Gli annunci possono essere visualizzati sia sotto forma di link pubblicitari che sotto forma di banner in varie forme grafiche.<br \/>\nIl click sull\u2019icona o sul banner pubblicato su questo Sito Web sono tracciati dai servizi terzi elencati di seguito e vengono condivisi con questo Sito Web.<br \/>\nPer conoscere quali dati vengano raccolti si prega di far riferimento alle informative privacy di ciascun servizio.<\/p>\n<h4>AMAZON AFFILIATION (AMAZON)<\/h4>\n<p>Amazon Affiliation \u00e8 un servizio di affiliazione commerciale fornito da Amazon.com Inc.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.amazon.com\/gp\/help\/customer\/display.html\/ref=hp_rel_topic?ie=UTF8&amp;nodeId=468496\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_3581264\">CONTATTARE L\u2019UTENTE<\/h3>\n<h4>MODULO DI CONTATTO (QUESTO SITO WEB)<\/h4>\n<p>L\u2019Utente, compilando con i propri Dati il modulo di contatto, acconsente al loro utilizzo per rispondere alle richieste di informazioni, di preventivo, o di qualunque altra natura indicata dall\u2019intestazione del modulo.<\/p>\n<p>Dati Personali raccolti: email e nome.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_3581210\">GESTIONE CONTATTI E INVIO DI MESSAGGI<\/h3>\n<p>Questo tipo di servizi consente di gestire un database di contatti email, contatti telefonici o contatti di qualunque altro tipo, utilizzati per comunicare con l\u2019Utente.<br \/>\nQuesti servizi potrebbero inoltre consentire di raccogliere dati relativi alla data e all\u2019ora di visualizzazione dei messaggi da parte dell\u2019Utente, cos\u00ec come all\u2019interazione dell\u2019Utente con essi, come le informazioni sui click sui collegamenti inseriti nei messaggi.<\/p>\n<h4>MAILCHIMP (THE ROCKET SCIENCE GROUP, LLC.)<\/h4>\n<p>MailChimp \u00e8 un servizio di gestione indirizzi e invio di messaggi email fornito da The Rocket Science Group, LLC.<\/p>\n<p>Dati Personali raccolti: email.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/mailchimp.com\/legal\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_4751301\">HEAT MAPPING E REGISTRAZIONE SESSIONI<\/h3>\n<p>I servizi di heat mapping sono utilizzati per individuare quali aree di una pagina sono oggetto del passaggio del cursore o di click del mouse in modo da rilevare quali di esse attraggono il maggior interesse. Questi servizi permettono di monitorare e analizzare i dati di traffico e servono a tener traccia del comportamento dell\u2019Utente.<br \/>\nAlcuni di questi servizi potrebbero registrare le sessioni e renderle disponibili per visualizzarle in seguito.<\/p>\n<h4>SMARTLOOK (SMARTSUPP.COM, S.R.O.)<\/h4>\n<p>Smartlook \u00e8 un servizio di heat mapping e di registrazione delle sessioni fornito da Smartsupp.com, s.r.o.<\/p>\n<p>Dati Personali raccolti: Cookie, Dati di utilizzo e varie tipologie di Dati secondo quanto specificato dalla privacy policy del servizio.<\/p>\n<p>Luogo del trattamento: Repubblica Ceca \u2013\u00a0<a href=\"https:\/\/www.smartlook.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_3581367\">INTERAZIONE CON SOCIAL NETWORK E PIATTAFORME ESTERNE<\/h3>\n<p>Questo tipo di servizi permette di effettuare interazioni con i social network, o con altre piattaforme esterne, direttamente dalle pagine di questo Sito Web.<br \/>\nLe interazioni e le informazioni acquisite da questo Sito Web sono in ogni caso soggette alle impostazioni privacy dell\u2019Utente relative ad ogni social network.<br \/>\nNel caso in cui sia installato un servizio di interazione con i social network, \u00e8 possibile che, anche nel caso gli Utenti non utilizzino il servizio, lo stesso raccolga dati di traffico relativi alle pagine in cui \u00e8 installato.<\/p>\n<h4>PULSANTE E WIDGET SOCIALI DI LINKEDIN (LINKEDIN CORPORATION)<\/h4>\n<p>Il pulsante e i widget sociali di LinkedIn sono servizi di interazione con il social network Linkedin, forniti da LinkedIn Corporation.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h4>PULSANTE MI PIACE E WIDGET SOCIALI DI FACEBOOK (FACEBOOK, INC.)<\/h4>\n<p>Il pulsante \u201cMi Piace\u201d e i widget sociali di Facebook sono servizi di interazione con il social network Facebook, forniti da Facebook, Inc.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/www.facebook.com\/privacy\/explanation\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h4>PULSANTE TWEET E WIDGET SOCIALI DI TWITTER (TWITTER, INC.)<\/h4>\n<p>Il pulsante Tweet e i widget sociali di Twitter sono servizi di interazione con il social network Twitter, forniti da Twitter, Inc.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/twitter.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_4751312\">REMARKETING E BEHAVIORAL TARGETING<\/h3>\n<p>Questo tipo di servizi consente a questo Sito Web ed ai suoi partner di comunicare, ottimizzare e servire annunci pubblicitari basati sull\u2019utilizzo passato di questo Sito Web da parte dell\u2019Utente.<br \/>\nQuesta attivit\u00e0 viene effettuata tramite il tracciamento dei Dati di Utilizzo e l\u2019uso di Cookie, informazioni che vengono trasferite ai partner a cui l\u2019attivit\u00e0 di remarketing e behavioral targeting \u00e8 collegata.<br \/>\nIn aggiunta alle possibilit\u00e0 di effettuare l\u2019opt-out offerte dai servizi di seguito riportati, l\u2019Utente pu\u00f2 optare per l\u2019esclusione rispetto alla ricezione dei cookie relativi ad un servizio terzo, visitando la\u00a0<a href=\"http:\/\/optout.networkadvertising.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">pagina di opt-out del Network Advertising Initiative<\/a>.<\/p>\n<h4>ADWORDS REMARKETING (GOOGLE INC.)<\/h4>\n<p>AdWords Remarketing \u00e8 un servizio di remarketing e behavioral targeting fornito da Google Inc. che collega l\u2019attivit\u00e0 di questo Sito Web con il network di advertising Adwords ed il Cookie Doubleclick.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.google.com\/intl\/it\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/www.google.com\/settings\/ads\/onweb\/optout\" target=\"_blank\" rel=\"noopener noreferrer\">Opt Out<\/a>.<\/p>\n<h4>FACEBOOK CUSTOM AUDIENCE (FACEBOOK, INC.)<\/h4>\n<p>Facebook Custom Audience \u00e8 un servizio di remarketing e behavioral targeting fornito da Facebook, Inc. che collega l\u2019attivit\u00e0 di questo Sito Web con il network di advertising Facebook.<\/p>\n<p>Dati Personali raccolti: Cookie e email.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/www.aboutads.info\/choices\/\" target=\"_blank\" rel=\"noopener noreferrer\">Opt Out<\/a>. Soggetto aderente al Privacy Shield.<\/p>\n<h4>FACEBOOK REMARKETING (FACEBOOK, INC.)<\/h4>\n<p>Facebook Remarketing \u00e8 un servizio di remarketing e behavioral targeting fornito da Facebook, Inc. che collega l\u2019attivit\u00e0 di questo Sito Web con il network di advertising Facebook.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/www.aboutads.info\/choices\/\" target=\"_blank\" rel=\"noopener noreferrer\">Opt Out<\/a>. Soggetto aderente al Privacy Shield.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_3581198\">STATISTICA<\/h3>\n<p>I servizi contenuti nella presente sezione permettono al Titolare del Trattamento di monitorare e analizzare i dati di traffico e servono a tener traccia del comportamento dell\u2019Utente.<\/p>\n<h4>GOOGLE ANALYTICS CON IP ANONIMIZZATO (GOOGLE INC.)<\/h4>\n<p>Google Analytics \u00e8 un servizio di analisi web fornito da Google Inc. (\u201cGoogle\u201d). Google utilizza i Dati Personali raccolti allo scopo di tracciare ed esaminare l\u2019utilizzo di questo Sito Web, compilare report e condividerli con gli altri servizi sviluppati da Google.<br \/>\nGoogle potrebbe utilizzare i Dati Personali per contestualizzare e personalizzare gli annunci del proprio network pubblicitario.<br \/>\nQuesta integrazione di Google Analytics rende anonimo il tuo indirizzo IP. L\u2019anonimizzazione funziona abbreviando entro i confini degli stati membri dell\u2019Unione Europea o in altri Paesi aderenti all\u2019accordo sullo Spazio Economico Europeo l\u2019indirizzo IP degli Utenti. Solo in casi eccezionali, l\u2019indirizzo IP sar\u00e0 inviato ai server di Google ed abbreviato all\u2019interno degli Stati Uniti.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/www.google.com\/intl\/it\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=it\" target=\"_blank\" rel=\"noopener noreferrer\">Opt Out<\/a>.<\/p>\n<h4>MONITORAGGIO CONVERSIONI DI FACEBOOK ADS (FACEBOOK, INC.)<\/h4>\n<p>Il monitoraggio conversioni di Facebook Ads \u00e8 un servizio di statistiche fornito da Facebook, Inc. che collega i dati provenienti dal network di annunci Facebook con le azioni compiute all\u2019interno di questo Sito Web.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>. Soggetto aderente al Privacy Shield.<\/p>\n<h3 class=\"expand-click w_icon_24 policyicon_purpose_3581208\">VISUALIZZAZIONE DI CONTENUTI DA PIATTAFORME ESTERNE<\/h3>\n<p>Questo tipo di servizi permette di visualizzare contenuti ospitati su piattaforme esterne direttamente dalle pagine di questo Sito Web e di interagire con essi.<br \/>\nNel caso in cui sia installato un servizio di questo tipo, \u00e8 possibile che, anche nel caso gli Utenti non utilizzino il servizio, lo stesso raccolga dati di traffico relativi alle pagine in cui \u00e8 installato.<\/p>\n<h4>VIDEO VIMEO (VIMEO, LLC)<\/h4>\n<p>Vimeo \u00e8 un servizio di visualizzazione di contenuti video gestito da Vimeo, LLC che permette a questo Sito Web di integrare tali contenuti all\u2019interno delle proprie pagine.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: USA \u2013\u00a0<a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h4>WIDGET GOOGLE MAPS (GOOGLE INC.)<\/h4>\n<p>Google Maps \u00e8 un servizio di visualizzazione di mappe gestito da Google Inc. che permette a questo Sito Web di integrare tali contenuti all\u2019interno delle proprie pagine.<\/p>\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n<p>Luogo del trattamento: Stati Uniti \u2013\u00a0<a href=\"https:\/\/www.google.it\/intl\/it\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>. Soggetto aderente al Privacy Shield.<\/p>\n<h2>DIRITTI DELL\u2019UTENTE<\/h2>\n<p>Gli Utenti possono esercitare determinati diritti con riferimento ai Dati trattati dal Titolare.<\/p>\n<p>In particolare, l\u2019Utente ha il diritto di:<\/p>\n<ul>\n<li><b>revocare il consenso in ogni momento.<\/b>\u00a0L\u2019Utente pu\u00f2 revocare il consenso al trattamento dei propri Dati Personali precedentemente espresso.<\/li>\n<li><b>opporsi al trattamento dei propri Dati.<\/b>\u00a0L\u2019Utente pu\u00f2 opporsi al trattamento dei propri Dati quando esso avviene su una base giuridica diversa dal consenso. Ulteriori dettagli sul diritto di opposizione sono indicati nella sezione sottostante.<\/li>\n<li><b>accedere ai propri Dati.<\/b>\u00a0L\u2019Utente ha diritto ad ottenere informazioni sui Dati trattati dal Titolare, su determinati aspetti del trattamento ed a ricevere una copia dei Dati trattati.<\/li>\n<li><b>verificare e chiedere la rettificazione.<\/b>\u00a0L\u2019Utente pu\u00f2 verificare la correttezza dei propri Dati e richiederne l\u2019aggiornamento o la correzione.<\/li>\n<li><b>ottenere la limitazione del trattamento.<\/b>\u00a0Quando ricorrono determinate condizioni, l\u2019Utente pu\u00f2 richiedere la limitazione del trattamento dei propri Dati. In tal caso il Titolare non tratter\u00e0 i Dati per alcun altro scopo se non la loro conservazione.<\/li>\n<li><b>ottenere la cancellazione o rimozione dei propri Dati Personali.<\/b>\u00a0Quando ricorrono determinate condizioni, l\u2019Utente pu\u00f2 richiedere la cancellazione dei propri Dati da parte del Titolare.<\/li>\n<li><b>ricevere i propri Dati o farli trasferire ad altro titolare.<\/b>\u00a0L\u2019Utente ha diritto di ricevere i propri Dati in formato strutturato, di uso comune e leggibile da dispositivo automatico e, ove tecnicamente fattibile, di ottenerne il trasferimento senza ostacoli ad un altro titolare. Questa disposizione \u00e8 applicabile quando i Dati sono trattati con strumenti automatizzati ed il trattamento \u00e8 basato sul consenso dell\u2019Utente, su un contratto di cui l\u2019Utente \u00e8 parte o su misure contrattuali ad esso connesse.<\/li>\n<li><b>proporre reclamo.<\/b>\u00a0L\u2019Utente pu\u00f2 proporre un reclamo all\u2019autorit\u00e0 di controllo della protezione dei dati personali competente o agire in sede giudiziale.<\/li>\n<\/ul>\n<h3>DETTAGLI SUL DIRITTO DI OPPOSIZIONE<\/h3>\n<p>Quando i Dati Personali sono trattati nell\u2019interesse pubblico, nell\u2019esercizio di pubblici poteri di cui \u00e8 investito il Titolare oppure per perseguire un interesse legittimo del Titolare, gli Utenti hanno diritto ad opporsi al trattamento per motivi connessi alla loro situazione particolare.<\/p>\n<p>Si fa presente agli Utenti che, ove i loro Dati fossero trattati con finalit\u00e0 di marketing diretto, possono opporsi al trattamento senza fornire alcuna motivazione. Per scoprire se il Titolare tratti dati con finalit\u00e0 di marketing diretto gli Utenti possono fare riferimento alle rispettive sezioni di questo documento.<\/p>\n<h3>COME ESERCITARE I DIRITTI<\/h3>\n<p>Per esercitare i diritti dell\u2019Utente, gli Utenti possono indirizzare una richiesta agli estremi di contatto del Titolare indicati in questo documento. Le richieste sono depositate a titolo gratuito e evase dal Titolare nel pi\u00f9 breve tempo possibile, in ogni caso entro un mese.<\/p>\n<h2 id=\"cookie_policy\">COOKIE POLICY<\/h2>\n<p>Questo Sito Web fa utilizzo di Cookie. Per saperne di pi\u00f9 e per prendere visione dell\u2019informativa dettagliata, l\u2019Utente pu\u00f2 consultare la\u00a0<a class=\"show_comp_link iframe-preserve an-preserve\" title=\"Cookie Policy\" href=\"https:\/\/www.psicologoberlino.com\/cookie\">Cookie Policy<\/a>.<\/p>\n<h2 id=\"further_data_processing_info\">ULTERIORI INFORMAZIONI SUL TRATTAMENTO<\/h2>\n<h3>DIFESA IN GIUDIZIO<\/h3>\n<p>I Dati Personali dell\u2019Utente possono essere utilizzati da parte del Titolare in giudizio o nelle fasi preparatorie alla sua eventuale instaurazione per la difesa da abusi nell\u2019utilizzo di questo Sito Web o dei Servizi connessi da parte dell\u2019Utente.<br \/>\nL\u2019Utente dichiara di essere consapevole che il Titolare potrebbe essere obbligato a rivelare i Dati per ordine delle autorit\u00e0 pubbliche.<\/p>\n<h3>INFORMATIVE SPECIFICHE<\/h3>\n<p>Su richiesta dell\u2019Utente, in aggiunta alle informazioni contenute in questa privacy policy, questo Sito Web potrebbe fornire all\u2019Utente delle informative aggiuntive e contestuali riguardanti Servizi specifici, o la raccolta ed il trattamento di Dati Personali.<\/p>\n<h3>LOG DI SISTEMA E MANUTENZIONE<\/h3>\n<p>Per necessit\u00e0 legate al funzionamento ed alla manutenzione, questo Sito Web e gli eventuali servizi terzi da essa utilizzati potrebbero raccogliere Log di sistema, ossia file che registrano le interazioni e che possono contenere anche Dati Personali, quali l\u2019indirizzo IP Utente.<\/p>\n<h3>INFORMAZIONI NON CONTENUTE IN QUESTA POLICY<\/h3>\n<p>Ulteriori informazioni in relazione al trattamento dei Dati Personali potranno essere richieste in qualsiasi momento al Titolare del Trattamento utilizzando gli estremi di contatto.<\/p>\n<h3>RISPOSTA ALLE RICHIESTE \u201eDO NOT TRACK\u201d<\/h3>\n<p>Questo Sito Web non supporta le richieste \u201cDo Not Track\u201d.<br \/>\nPer scoprire se gli eventuali servizi di terze parti utilizzati le supportino, l\u2019Utente \u00e8 invitato a consultare le rispettive privacy policy.<\/p>\n<h3>MODIFICHE A QUESTA PRIVACY POLICY<\/h3>\n<p>Il Titolare del Trattamento si riserva il diritto di apportare modifiche alla presente privacy policy in qualunque momento dandone informazione agli Utenti su questa pagina e, se possibile, su questo Sito Web nonch\u00e9, qualora tecnicamente e legalmente fattibile, inviando una notifica agli Utenti attraverso uno degli estremi di contatto di cui \u00e8 in possesso il Titolare . Si prega dunque di consultare regolarmente questa pagina, facendo riferimento alla data di ultima modifica indicata in fondo.<\/p>\n<p>Qualora le modifiche interessino trattamenti la cui base giuridica \u00e8 il consenso, il Titolare provveder\u00e0 a raccogliere nuovamente il consenso dell\u2019Utente, se necessario.<\/p>\n<h3 class=\"expand-click w_icon_24 icon_ribbon\">DEFINIZIONI E RIFERIMENTI LEGALI<\/h3>\n<h4>DATI PERSONALI (O DATI)<\/h4>\n<p>Costituisce dato personale qualunque informazione che, direttamente o indirettamente, anche in collegamento con qualsiasi altra informazione, ivi compreso un numero di identificazione personale, renda identificata o identificabile una persona fisica.<\/p>\n<h4>DATI DI UTILIZZO<\/h4>\n<p>Sono le informazioni raccolte automaticamente attraverso questo Sito Web (anche da applicazioni di parti terze integrate in questo Sito Web), tra cui: gli indirizzi IP o i nomi a dominio dei computer utilizzati dall\u2019Utente che si connette con questo Sito Web, gli indirizzi in notazione URI (Uniform Resource Identifier), l\u2019orario della richiesta, il metodo utilizzato nell\u2019inoltrare la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta dal server (buon fine, errore, ecc.) il paese di provenienza, le caratteristiche del browser e del sistema operativo utilizzati dal visitatore, le varie connotazioni temporali della visita (ad esempio il tempo di permanenza su ciascuna pagina) e i dettagli relativi all\u2019itinerario seguito all\u2019interno dell\u2019Applicazione, con particolare riferimento alla sequenza delle pagine consultate, ai parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019Utente.<\/p>\n<h4>UTENTE<\/h4>\n<p>L\u2019individuo che utilizza questo Sito Web che, salvo ove diversamente specificato, coincide con l\u2019Interessato.<\/p>\n<h4>INTERESSATO<\/h4>\n<p>La persona fisica cui si riferiscono i Dati Personali.<\/p>\n<h4>RESPONSABILE DEL TRATTAMENTO (O RESPONSABILE)<\/h4>\n<p>La persona fisica, giuridica, la pubblica amministrazione e qualsiasi altro ente che tratta dati personali per conto del Titolare, secondo quanto esposto nella presente privacy policy.<\/p>\n<h4>TITOLARE DEL TRATTAMENTO (O TITOLARE)<\/h4>\n<p>La persona fisica o giuridica, l\u2019autorit\u00e0 pubblica, il servizio o altro organismo che, singolarmente o insieme ad altri, determina le finalit\u00e0 e i mezzi del trattamento di dati personali e gli strumenti adottati, ivi comprese le misure di sicurezza relative al funzionamento ed alla fruizione di questo Sito Web. Il Titolare del Trattamento, salvo quanto diversamente specificato, \u00e8 il titolare di questo Sito Web.<\/p>\n<h4>QUESTO SITO WEB (O QUESTA APPLICAZIONE)<\/h4>\n<p>Lo strumento hardware o software mediante il quale sono raccolti e trattati i Dati Personali degli Utenti.<\/p>\n<h4>SERVIZIO<\/h4>\n<p>Il Servizio fornito da questo Sito Web cos\u00ec come definito nei relativi termini (se presenti) su questo sito\/applicazione.<\/p>\n<h4>UNIONE EUROPEA (O UE)<\/h4>\n<p>Salvo ove diversamente specificato, ogni riferimento all\u2019Unione Europea contenuto in questo documento si intende esteso a tutti gli attuali stati membri dell\u2019Unione Europea e dello Spazio Economico Europeo.<\/p>\n<h4>COOKIE<\/h4>\n<p>Piccola porzione di dati conservata all\u2019interno del dispositivo dell\u2019Utente.<\/p>\n<hr \/>\n<h4>RIFERIMENTI LEGALI<\/h4>\n<p>La presente informativa privacy \u00e8 redatta sulla base di molteplici ordinamenti legislativi, inclusi gli artt. 13 e 14 del Regolamento (UE) 2016\/679.<\/p>\n<p>Ove non diversamente specificato, questa informativa privacy riguarda esclusivamente questo Sito Web.<\/p>\n<p>&nbsp;<\/p>\n<p>Ultima modifica del documento: 26\/11\/2019<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] DATENSCHUTZERKL\u00c4RUNG DI WWW.PSICOLOGOBERLINO.COM Questo Sito Web raccoglie alcuni Dati Personali dei propri Utenti. TITOLARE DEL TRATTAMENTO DEI DATI Caterina Nicolosi Gan\u00dfmann \u2013 Karl Schrader Str. 6 10781 Berlin Sch\u00f6neberg (Germania) Indirizzo email del Titolare:\u00a0info@psicologoberlino.com TIPOLOGIE DI DATI RACCOLTI Fra i Dati Personali raccolti da questo Sito Web, in modo autonomo o tramite terze parti, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3578","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutzerkl\u00e4rung - Caterina Nicolosi Gan\u00dfmann<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/psicologoberlino.com\/de\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - Caterina Nicolosi Gan\u00dfmann\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] DATENSCHUTZERKL\u00c4RUNG DI WWW.PSICOLOGOBERLINO.COM Questo Sito Web raccoglie alcuni Dati Personali dei propri Utenti. TITOLARE DEL TRATTAMENTO DEI DATI Caterina Nicolosi Gan\u00dfmann \u2013 Karl Schrader Str. 6 10781 Berlin Sch\u00f6neberg (Germania) Indirizzo email del Titolare:\u00a0info@psicologoberlino.com TIPOLOGIE DI DATI RACCOLTI Fra i Dati Personali raccolti da questo Sito Web, in modo autonomo o tramite terze parti, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/psicologoberlino.com\/de\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Caterina Nicolosi Gan\u00dfmann\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T20:29:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"40\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/psicologoberlino.com\\\/de\\\/datenschutzerklaerung\\\/\",\"url\":\"https:\\\/\\\/psicologoberlino.com\\\/de\\\/datenschutzerklaerung\\\/\",\"name\":\"Datenschutzerkl\u00e4rung - Caterina Nicolosi Gan\u00dfmann\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/psicologoberlino.com\\\/de\\\/#website\"},\"datePublished\":\"2024-03-17T21:21:54+00:00\",\"dateModified\":\"2024-06-19T20:29:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/psicologoberlino.com\\\/de\\\/datenschutzerklaerung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/psicologoberlino.com\\\/de\\\/datenschutzerklaerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/psicologoberlino.com\\\/de\\\/datenschutzerklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/psicologoberlino.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/psicologoberlino.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/psicologoberlino.com\\\/de\\\/\",\"name\":\"Caterina Nicolosi Gan\u00dfmann\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/psicologoberlino.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - Caterina Nicolosi Gan\u00dfmann","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/psicologoberlino.com\/de\/datenschutzerklaerung\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - Caterina Nicolosi Gan\u00dfmann","og_description":"[vc_row][vc_column][vc_column_text] DATENSCHUTZERKL\u00c4RUNG DI WWW.PSICOLOGOBERLINO.COM Questo Sito Web raccoglie alcuni Dati Personali dei propri Utenti. TITOLARE DEL TRATTAMENTO DEI DATI Caterina Nicolosi Gan\u00dfmann \u2013 Karl Schrader Str. 6 10781 Berlin Sch\u00f6neberg (Germania) Indirizzo email del Titolare:\u00a0info@psicologoberlino.com TIPOLOGIE DI DATI RACCOLTI Fra i Dati Personali raccolti da questo Sito Web, in modo autonomo o tramite terze parti, [&hellip;]","og_url":"https:\/\/psicologoberlino.com\/de\/datenschutzerklaerung\/","og_site_name":"Caterina Nicolosi Gan\u00dfmann","article_modified_time":"2024-06-19T20:29:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"40\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/psicologoberlino.com\/de\/datenschutzerklaerung\/","url":"https:\/\/psicologoberlino.com\/de\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung - Caterina Nicolosi Gan\u00dfmann","isPartOf":{"@id":"https:\/\/psicologoberlino.com\/de\/#website"},"datePublished":"2024-03-17T21:21:54+00:00","dateModified":"2024-06-19T20:29:10+00:00","breadcrumb":{"@id":"https:\/\/psicologoberlino.com\/de\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/psicologoberlino.com\/de\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/psicologoberlino.com\/de\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/psicologoberlino.com\/de\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/psicologoberlino.com\/de\/#website","url":"https:\/\/psicologoberlino.com\/de\/","name":"Caterina Nicolosi Gan\u00dfmann","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/psicologoberlino.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/psicologoberlino.com\/de\/wp-json\/wp\/v2\/pages\/3578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psicologoberlino.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/psicologoberlino.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/psicologoberlino.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/psicologoberlino.com\/de\/wp-json\/wp\/v2\/comments?post=3578"}],"version-history":[{"count":1,"href":"https:\/\/psicologoberlino.com\/de\/wp-json\/wp\/v2\/pages\/3578\/revisions"}],"predecessor-version":[{"id":3579,"href":"https:\/\/psicologoberlino.com\/de\/wp-json\/wp\/v2\/pages\/3578\/revisions\/3579"}],"wp:attachment":[{"href":"https:\/\/psicologoberlino.com\/de\/wp-json\/wp\/v2\/media?parent=3578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}